{"id":2898,"date":"2022-12-10T17:55:48","date_gmt":"2022-12-10T15:55:48","guid":{"rendered":"http:\/\/104.248.46.37\/non-classifiee\/clinique-dentaire\/"},"modified":"2026-03-02T18:47:28","modified_gmt":"2026-03-02T16:47:28","slug":"clinique-dentaire","status":"publish","type":"post","link":"https:\/\/craftandconcept.ch\/fr\/architecture-fr\/clinique-dentaire\/","title":{"rendered":"CLINIQUE DENTAIRE"},"content":{"rendered":"<p>Un b\u00e2timent abandonn\u00e9 de l&rsquo;\u00e8re sovi\u00e9tique est en train d&rsquo;\u00eatre transform\u00e9 en une clinique dentaire avec un centre de formation. Malgr\u00e9 le fait que le b\u00e2timent n&rsquo;a aucune valeur historique, il a \u00e9t\u00e9 d\u00e9cid\u00e9 de conserver ses caract\u00e9ristiques et proportions de base, ainsi que l\u2019apparence des fa\u00e7ades. Dans ces pi\u00e8ces, dont le fonctionnement n\u00e9cessite plus de lumi\u00e8re naturelle, les ouvertures des fen\u00eatres ont \u00e9t\u00e9 agrandies. Les nouvelles couleurs du pl\u00e2tre de fa\u00e7ade et des montants de fen\u00eatres sont traditionnelles pour les b\u00e2timents historiques de Kharkiv &#8211; ce sont des murs gris fonc\u00e9 et des cadres de fen\u00eatres rouges. Les accents sont les volumes caract\u00e9ristiques de nouveaux \u00e9l\u00e9ments du b\u00e2timent &#8211; la r\u00e9ception, le balcon et la salle d&rsquo;ing\u00e9nierie sur le toit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un b\u00e2timent abandonn\u00e9 de l&rsquo;\u00e8re sovi\u00e9tique est en train d&rsquo;\u00eatre transform\u00e9 en une clinique dentaire avec un centre de formation. Malgr\u00e9 le fait que le b\u00e2timent n&rsquo;a aucune valeur historique, il a \u00e9t\u00e9 d\u00e9cid\u00e9 de conserver ses caract\u00e9ristiques et proportions de base, ainsi que l\u2019apparence des fa\u00e7ades. Dans ces pi\u00e8ces, dont le fonctionnement n\u00e9cessite plus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-2898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architecture-fr","style-minimalisme"],"_links":{"self":[{"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/posts\/2898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/comments?post=2898"}],"version-history":[{"count":3,"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/posts\/2898\/revisions"}],"predecessor-version":[{"id":7757,"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/posts\/2898\/revisions\/7757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/media\/2116"}],"wp:attachment":[{"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/media?parent=2898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/categories?post=2898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/craftandconcept.ch\/fr\/wp-json\/wp\/v2\/tags?post=2898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}